{"id":262,"date":"2012-11-01T05:00:20","date_gmt":"2012-11-01T07:00:20","guid":{"rendered":"http:\/\/www.encontrasavassi.com.br\/noticias\/?p=262"},"modified":"2013-08-19T10:41:20","modified_gmt":"2013-08-19T12:41:20","slug":"metro-savassibelvedere-estudo-da-bhtrans-aponta-que-sim","status":"publish","type":"post","link":"https:\/\/www.encontrasavassi.com.br\/noticias\/metro-savassibelvedere-estudo-da-bhtrans-aponta-que-sim\/","title":{"rendered":"Metr\u00f4 Savassi\/Belvedere Estudo da BHTrans aponta que sim"},"content":{"rendered":"<p>Um estudo encomendado pela BHTrans avaliou: qual a melhor forma de transporte entre a Savassi e o Belvedere? A resposta foi: metr\u00f4.<\/p>\n<div>\n<p>A avalia\u00e7\u00e3o, realizada pela empresa belo-horizontina Planum, durou dois anos e estudou as possibilidades de transporte p\u00fablico no chamado \u201cvetor-sul\u201d, que realiza a liga\u00e7\u00e3o da regi\u00e3o do Belvedere ao Centro, passando pela Savassi via avenida Nossa Senhora do Carmo.<\/p>\n<p>Como explica o\u00a0assessor de rela\u00e7\u00f5es metropolitanas e metr\u00f4 da BHTrans, Tom\u00e1s Ahouagi, o estudo comparou as seguintes modalidades:<\/p>\n<ul>\n<li>metr\u00f4 \u2013 em duas alternativas: uma seguindo direto pela avenida Nossa Senhora do Carmo e outra com uma entrada na Avenida Uruguai<\/li>\n<li>BRT, que est\u00e1 sendo instalado na avenida Ant\u00f4nio Carlos e na Cristiano Machado<\/li>\n<li>VLT (Ve\u00edculo Leve sobre Trilhos), uma esp\u00e9cie de bonde leve que roda em trilhos<\/li>\n<li>VLP (Ve\u00edculo Leve sobre Pneus), uma vers\u00e3o do VLT que possui rodas<\/li>\n<li>monotrilho, que segue em um trilho suspenso acima das ruas e avenida<\/li>\n<\/ul>\n<\/div>\n<p>A avalia\u00e7\u00e3o levou em considera\u00e7\u00e3o crit\u00e9rios como custo de instala\u00e7\u00e3o e opera\u00e7\u00e3o, desempenhos econ\u00f4micos, impactos ambientais, impactos urbanos (como necessidade de desapropria\u00e7\u00e3o) e impactos visuais, dentre outros. A estimativa \u00e9 que o trecho Savassi\/Belvedere do metr\u00f4 transporte 10 mil pessoas por hora em cada sentido nos pr\u00f3ximos 20 anos.<\/p>\n<p>\u201cNenhuma alternativa \u00e9 perfeita. O metr\u00f4 \u00e9 uma op\u00e7\u00e3o cara, a manuten\u00e7\u00e3o n\u00e3o se paga apenas com a passagem, \u00e9 \u00a0necess\u00e1rio subs\u00eddios. O BRT, apesar de mais barato, ocupa muito espa\u00e7o e requer desapropria\u00e7\u00e3o \u2013 e n\u00e3o vamos desapropriar na Savassi. J\u00e1 o monotrilho n\u00e3o pode passar por qualquer lugar, por exemplo, em cima da Pra\u00e7a da Liberdade, e ele precisa ter esta\u00e7\u00f5es a cada 700m\u201d, explica Tom\u00e1s.<\/p>\n<p>Em uma linha reta imagin\u00e1ria, s\u00e3o cerca de 4 km separando a Pra\u00e7a da Savassi do Belvedere, na altura do BH Shopping. Seguindo de carro, pela avenida Nossa Senhora do Carmo, s\u00e3o aproximadamente 5 km. Nesse \u201cpequeno\u201d trecho \u2013 menos da metade dos 12 km que separam a Savassi da Pampulha, por exemplo -, passam cerca de 60 mil ve\u00edculos por dia, segundo a BHTrans.\u00a0Para se ter uma ideia, a circula\u00e7\u00e3o nesse trecho \u00e9 similar \u00e0 da avenida Amazonas ou da Pedro II e cerca de metade dos 120 mil ve\u00edculos que circulam pelo Anel Rodovi\u00e1rio diariamente.<\/p>\n<p>De acordo com Tom\u00e1s, o estudo tem apenas car\u00e1ter explorat\u00f3rio e n\u00e3o h\u00e1 ainda um projeto de extens\u00e3o do metr\u00f4 at\u00e9 o Belvedere. A ideia \u00e9 que essa avalia\u00e7\u00e3o sirva como embasamento para decis\u00f5es futuras. \u201cO \u2018vetor sul\u2019 tem uma densidade habitacional alta e gera muitos empregos \u2013 muitas as pessoas v\u00eam de outros bairros e da Regi\u00e3o Metropolitana para trabalhar nessa \u00e1rea. Al\u00e9m disso, devido \u00e0 alta renda de quem mora na regi\u00e3o, h\u00e1 muitos carros. Como n\u00e3o \u00e9 poss\u00edvel alargar a Nossa Senhora do Carmo ou colocar um minhoc\u00e3o em cima da Contorno, \u00e9 previso investir em boas op\u00e7\u00f5es de transporte p\u00fablico para solucionar o tr\u00e2nsito na regi\u00e3o\u201d, comenta.<\/p>\n<p>Atualmente, a expans\u00e3o do metr\u00f4 da cidade de Belo Horizonte est\u00e1 na fase de sondagem. S\u00e3o cerca de\u00a0150 furos de sondagem, de 30 a 50 metros de profundidade. Com as perfura\u00e7\u00f5es, a empresa quer obter amostras e informa\u00e7\u00f5es sobre a resist\u00eancia das camadas do solo, o n\u00edvel da \u00e1gua subterr\u00e2nea e os tipos de rocha existentes no local.<\/p>\n<p>Os trabalhos, que come\u00e7aram em setembro, est\u00e3o previstos para serem conclu\u00eddos at\u00e9 o final do ano.\u00a0S\u00f3 a partir desse trabalho \u00e9 que ser\u00e1 elaborado o projeto b\u00e1sico de engenharia para a amplia\u00e7\u00e3o do metr\u00f4.<\/p>\n<p>A Linha 1, da esta\u00e7\u00e3o Eldorado, em Contagem, at\u00e9 a esta\u00e7\u00e3o Vilarinho, em Venda Nova, ser\u00e1 ampliada em 1,7 km at\u00e9 o Novo Eldorado e deve receber novos trens e reformas nas esta\u00e7\u00f5es e nos sistemas el\u00e9trico e de comunica\u00e7\u00e3o.\u00a0A Linha 2 ir\u00e1 receber o trecho Barreiro\/Calafate.\u00a0J\u00e1 a Linha 3, dever\u00e1 ser inaugurada com o trecho Savassi \u00e0 Lagoinha.\u00a0O \u00fanico trecho que deve ficar pronto antes da Copa de 2014 \u00e9 a moderniza\u00e7\u00e3o da Linha 1. A previs\u00e3o para o final das obras \u00e9 em 2016.<\/p>\n<p>Ao todo, as obras ir\u00e3o custar R$ 3,05 bilh\u00f5es, sendo R$ 1,75 bilh\u00e3o do Governo Federal e R$ 1,3 bilh\u00e3o do Governo de estado de Minas Gerais, das Prefeituras de Belo Horizonte e Contagem e atrav\u00e9s de Parceria P\u00fablico Privada.<\/p>\n<p><em>Fonte: Na Savassi<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um estudo encomendado pela BHTrans avaliou: qual a melhor forma de transporte entre a Savassi e o Belvedere? A resposta foi: metr\u00f4. A avalia\u00e7\u00e3o, realizada pela empresa belo-horizontina Planum, durou dois anos e estudou as possibilidades de transporte p\u00fablico no chamado \u201cvetor-sul\u201d, que realiza a liga\u00e7\u00e3o da regi\u00e3o do Belvedere ao Centro, passando pela Savassi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,8],"tags":[14],"class_list":["post-262","post","type-post","status-publish","format-standard","hentry","category-noticias","category-servicos","tag-savassi"],"_links":{"self":[{"href":"https:\/\/www.encontrasavassi.com.br\/noticias\/wp-json\/wp\/v2\/posts\/262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrasavassi.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrasavassi.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrasavassi.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrasavassi.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=262"}],"version-history":[{"count":6,"href":"https:\/\/www.encontrasavassi.com.br\/noticias\/wp-json\/wp\/v2\/posts\/262\/revisions"}],"predecessor-version":[{"id":721,"href":"https:\/\/www.encontrasavassi.com.br\/noticias\/wp-json\/wp\/v2\/posts\/262\/revisions\/721"}],"wp:attachment":[{"href":"https:\/\/www.encontrasavassi.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrasavassi.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrasavassi.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}